{"id":25725,"date":"2007-06-09T00:00:00","date_gmt":"2007-06-09T05:00:00","guid":{"rendered":"https:\/\/www.dejusticia.org\/of-the-land-nothing\/"},"modified":"2017-04-11T07:22:24","modified_gmt":"2017-04-11T12:22:24","slug":"of-the-land-nothing","status":"publish","type":"post","link":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/","title":{"rendered":"Of the land, nothing"},"content":{"rendered":"<p>Lo dicho en el editorial de El Tiempo el pasado primero de junio ??Cr\u00f3nica de un fiasco?- es lo que muchas personas, instituciones y organizaciones sociales han se\u00f1alado acerca de la estrategia del actual gobierno en torno al problema de la tierra en Colombia. En suma, que van cinco a\u00f1os de gobierno ?2002-2007? y de aquello nada, pues todav\u00eda no ha sido posible ver el despegue de la pol\u00edtica de tierras. <\/p>\n<p>Ahora resulta que el problema de fondo es la estructura administrativa que este mismo gobierno invent\u00f3. Cuando en 2003 se suprimi\u00f3 el Instituto Colombiano para la Reforma Agraria (Incora), se hizo bajo el argumento de la eficiencia y con un prop\u00f3sito centralizador, como que la entidad que lo reemplaz\u00f3 ?el Instituto Colombiano de Desarrollo Rural (Incoder)? debi\u00f3 asumir sus funciones y las de otras entidades igualmente suprimidas, relacionadas con el sector. La nueva estructura supon\u00eda una determinada pol\u00edtica que responder\u00eda a uno de los principales problemas sociales vigentes desde hace mucho tiempo en Colombia: la distribuci\u00f3n y el uso adecuado de la tierra. <\/p>\n<p>Pero se trat\u00f3 de una suposici\u00f3n falsa, como lo han demostrado los hechos y lo corrobor\u00f3 el propio ministro de Agricultura, quien se\u00f1al\u00f3 en un informe publicado por El Tiempo sobre el tema, que en estos cuatro a\u00f1os se dedic\u00f3 a ?sanear y clarificar antes de profundizar m\u00e1s en la pol\u00edtica de entrega de tierras?. Mejor dicho, se mont\u00f3 una estructura administrativa ?el Incoder? sin saber exactamente para qu\u00e9. Lo \u00fanico cierto fue la evaluaci\u00f3n temprana que del Incoder hizo la Procuradur\u00eda, que mostr\u00f3 sus fallas cualitativas y cuantitativas, como la constataci\u00f3n de contar ahora con apenas la quinta parte de los funcionarios que antes ejecutaban la pol\u00edtica del sector. <\/p>\n<p>Uno de los proyectos bandera del gobierno, presentado desde la legislatura pasada, es el estatuto de desarrollo rural, cuya aprobaci\u00f3n se debi\u00f3 surtir en las sesiones extraordinarias convocadas por el gobierno al inicio del presente a\u00f1o, pues se trataba de una prioridad de \u00e9ste y ten\u00eda la ventaja de haber sido aprobado en comisi\u00f3n y plenaria del Senado en diciembre de 2006. Como es sabido, las sesiones extra fueron un fracaso, no s\u00f3lo para este proyecto, sino para otros de inter\u00e9s del gobierno, como el plan de desarrollo y el TLC. Pero el punto es que all\u00ed se iba a aprobar, entre otras cosas, el fortalecimiento del Incoder, como el ente encargado de la ejecuci\u00f3n de la pol\u00edtica de tierras incorporada, en parte, en el mencionado proyecto de estatuto de desarrollo rural. <\/p>\n<p>Sin embargo, en un giro de 180 grados, el ministerio de Agricultura propuso en el tercer debate en Comisi\u00f3n de la C\u00e1mara de Representantes, esta vez en sesiones ordinarias, el desmantelamiento del Incoder, que ya no conocer\u00e1 de los procedimientos de clarificaci\u00f3n, delimitaci\u00f3n, ocupaci\u00f3n, expropiaci\u00f3n y extinci\u00f3n del dominio de tierras. Y el disciplinado Congreso le viene caminando sin problema alguno a la nov\u00edsima propuesta. As\u00ed, resulta que ahora las mencionadas funciones, entre otras, pasar\u00e1n a manos de una unidad administrativa especial llamada Unidad Nacional de Tierras Rurales, dependiente del Ministerio de Agricultura, por cierto con expresa prohibici\u00f3n de ejercer funciones respecto ?de los bienes inmuebles rurales que se encuentren involucrados en procesos de reparaci\u00f3n de los que trata la Ley 975 de 2005 de Justicia y Paz; ni a los programas de reaserci\u00f3n?. La propuesta, as\u00ed concebida, fue aprobada en la Comisi\u00f3n Quinta de la C\u00e1mara de Representantes y s\u00f3lo le resta su paso por la plenaria de la misma antes de dos semanas. Valga decir aqu\u00ed que el entierro de tercera que padecer\u00e1 en breve el Incoder contrasta con el hecho de que hace apenas unos d\u00edas el propio gobierno, con la firma del ministro de Agricultura, expidi\u00f3 el Decreto 1660 de mayo 14 de 2007 que regula la permuta de predios de propiedad de los desplazados cuyo tr\u00e1mite se debe hacer ante el ente que, en el escenario legislativo, se est\u00e1 desmembrando. <\/p>\n<p>Esta situaci\u00f3n pone al descubierto la pol\u00edtica de ensayo y error del gobierno en materia de tierras, en donde lo \u00fanico que parece claro es el paso de un esquema administrativo centralizado ?que llev\u00f3 a la concentraci\u00f3n de varias funciones de distintas entidades en una sola, el Incoder? a uno hipercentralizado, como ser\u00eda el caso de la Unidad Nacional de Tierras, pues a pesar de postularse como una unidad administrativa especial con autonom\u00eda administrativa y financiera, no puede tener la misma independencia que tendr\u00eda un establecimiento p\u00fablico como lo fueron el Incora y el Incoder. Y no se la puede comparar, como se ha querido presentar, con otro tipo unidades administrativas especiales como la Aeron\u00e1utica Civil, pues esta tiene, adem\u00e1s, el rango de departamento administrativo; esto es, poco menos que un ministerio. <\/p>\n<p>Hay que decir que la propuesta de la Unidad Nacional de Tierras es coherente con otras acciones y propuestas del gobierno orientadas a radicalizar la centralizaci\u00f3n ?como el caso de las transferencias?, en un a\u00f1o electoral en el que la ejecuci\u00f3n de la inversi\u00f3n p\u00fablica se debe cuidar para que la realicen consejer\u00edas presidenciales tipo Acci\u00f3n Social o ministros ?culiprontos? ?como lo record\u00f3 Jaime Castro? y no entidades descentralizadas de todo tipo. <\/p>\n<p>En realidad, estamos ante un giro de 360 grados, pero con doble vuelta de comp\u00e1s; esto es, volviendo al punto de partida ?sin arranque en la pol\u00edtica de tierras y a punto de estrenar estructura burocr\u00e1tico administrativa sin saber muy bien para qu\u00e9?, pero eso s\u00ed, subrayando el car\u00e1cter centralizado de lo que pueda resultar. <\/p>\n<p>Danilo Rojas Betancourth<br \/>\nMiembro fundador de DeJuSticia<br \/>\nProfesor de la Universidad Nacional <\/p>\n<p>El Centro de Estudios de Derecho, Justicia y Sociedad ?DeJuSticia? (www.dejusticia.org), fue creado en 2003 por un grupo de profesores universitarios, con el fin de contribuir a debates sobre el derecho, las instituciones y las pol\u00edticas p\u00fablicas, con base en estudios rigurosos que promuevan la formaci\u00f3n de una ciudadan\u00eda sin exclusiones y la vigencia de la democracia, el Estado social de derecho y los derechos humanos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danilo Rojas of Dejusticia, calls attention to the politics of trial and error of the government on the matter of administrative organization for the execution of its land programs.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1022],"tags":[],"class_list":["post-25725","post","type-post","status-publish","format-standard","hentry","category-uncategorized","subcategory-studying-the-protection-of-rigths","medium-semana-en","post-scope-aaa-not-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Of the land, nothing - Dejusticia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Of the land, nothing\" \/>\n<meta property=\"og:description\" content=\"Danilo Rojas of Dejusticia, calls attention to the politics of trial and error of the government on the matter of administrative organization for the execution of its land programs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\" \/>\n<meta property=\"og:site_name\" content=\"Dejusticia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dejusticia\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-06-09T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T12:22:24+00:00\" \/>\n<meta name=\"author\" content=\"Danilo Rojas Betancourth (Socio inactivo)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:site\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danilo Rojas Betancourth (Socio inactivo)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\"},\"author\":{\"name\":\"Danilo Rojas Betancourth (Socio inactivo)\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d2e33b9414e0642c0a4680dbc3ddbd83\"},\"headline\":\"Of the land, nothing\",\"datePublished\":\"2007-06-09T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:22:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\"},\"wordCount\":1053,\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"inLanguage\":\"en-US\",\"copyrightYear\":\"2007\",\"copyrightHolder\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\",\"url\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\",\"name\":\"Of the land, nothing - Dejusticia\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#website\"},\"datePublished\":\"2007-06-09T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:22:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/develop.dejusticia.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Of the land, nothing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/develop.dejusticia.org\/#website\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"name\":\"Dejusticia\",\"description\":\"Centro de Estudios de Derecho, Justicia y Sociedad\",\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/develop.dejusticia.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\",\"name\":\"Dejusticia\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"contentUrl\":\"https:\/\/www.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"width\":1,\"height\":1,\"caption\":\"Dejusticia\"},\"image\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Dejusticia\/\",\"https:\/\/x.com\/dejusticia\",\"https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d2e33b9414e0642c0a4680dbc3ddbd83\",\"name\":\"Danilo Rojas Betancourth (Socio inactivo)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7750ee2640b7de90f8eeccf3d137dba8850c7e423ac371976e0c1bf00b8f85bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7750ee2640b7de90f8eeccf3d137dba8850c7e423ac371976e0c1bf00b8f85bf?s=96&d=mm&r=g\",\"caption\":\"Danilo Rojas Betancourth (Socio inactivo)\"},\"url\":\"https:\/\/develop.dejusticia.org\/en\/responsible\/danilo-rojas\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Of the land, nothing - Dejusticia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/","og_locale":"en_US","og_type":"article","og_title":"Of the land, nothing","og_description":"Danilo Rojas of Dejusticia, calls attention to the politics of trial and error of the government on the matter of administrative organization for the execution of its land programs.","og_url":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/","og_site_name":"Dejusticia","article_publisher":"https:\/\/www.facebook.com\/Dejusticia\/","article_published_time":"2007-06-09T05:00:00+00:00","article_modified_time":"2017-04-11T12:22:24+00:00","author":"Danilo Rojas Betancourth (Socio inactivo)","twitter_card":"summary_large_image","twitter_creator":"@dejusticia","twitter_site":"@dejusticia","twitter_misc":{"Written by":"Danilo Rojas Betancourth (Socio inactivo)","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","NewsArticle"],"@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#article","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/"},"author":{"name":"Danilo Rojas Betancourth (Socio inactivo)","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d2e33b9414e0642c0a4680dbc3ddbd83"},"headline":"Of the land, nothing","datePublished":"2007-06-09T05:00:00+00:00","dateModified":"2017-04-11T12:22:24+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/"},"wordCount":1053,"publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"inLanguage":"en-US","copyrightYear":"2007","copyrightHolder":{"@id":"https:\/\/develop.dejusticia.org\/#organization"}},{"@type":"WebPage","@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/","url":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/","name":"Of the land, nothing - Dejusticia","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/#website"},"datePublished":"2007-06-09T05:00:00+00:00","dateModified":"2017-04-11T12:22:24+00:00","breadcrumb":{"@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/develop.dejusticia.org\/en\/of-the-land-nothing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/develop.dejusticia.org\/en\/"},{"@type":"ListItem","position":2,"name":"Of the land, nothing"}]},{"@type":"WebSite","@id":"https:\/\/develop.dejusticia.org\/#website","url":"https:\/\/develop.dejusticia.org\/","name":"Dejusticia","description":"Centro de Estudios de Derecho, Justicia y Sociedad","publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.dejusticia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/develop.dejusticia.org\/#organization","name":"Dejusticia","url":"https:\/\/develop.dejusticia.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","contentUrl":"https:\/\/www.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","width":1,"height":1,"caption":"Dejusticia"},"image":{"@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dejusticia\/","https:\/\/x.com\/dejusticia","https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed"]},{"@type":"Person","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d2e33b9414e0642c0a4680dbc3ddbd83","name":"Danilo Rojas Betancourth (Socio inactivo)","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7750ee2640b7de90f8eeccf3d137dba8850c7e423ac371976e0c1bf00b8f85bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7750ee2640b7de90f8eeccf3d137dba8850c7e423ac371976e0c1bf00b8f85bf?s=96&d=mm&r=g","caption":"Danilo Rojas Betancourth (Socio inactivo)"},"url":"https:\/\/develop.dejusticia.org\/en\/responsible\/danilo-rojas\/"}]}},"views":149,"translations":[{"es":{"translation_id":"9292","language_code":"es","element_id":"25724","source_language_code":null,"element_type":"post_post","original":"1","post_title":"Y de la tierra, nada","post_status":"publish"},"en":{"translation_id":"9293","language_code":"en","element_id":"25725","source_language_code":"es","element_type":"post_post","original":"0","post_title":"Of the land, nothing","post_status":"publish"}}],"_links":{"self":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/25725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/comments?post=25725"}],"version-history":[{"count":0,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/25725\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/media?parent=25725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/categories?post=25725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/tags?post=25725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}