{"id":26373,"date":"2009-07-11T00:00:00","date_gmt":"2009-07-11T05:00:00","guid":{"rendered":"https:\/\/www.dejusticia.org\/hard-against-drugs\/"},"modified":"2017-04-11T07:31:31","modified_gmt":"2017-04-11T12:31:31","slug":"hard-against-drugs","status":"publish","type":"post","link":"https:\/\/develop.dejusticia.org\/en\/hard-against-drugs\/","title":{"rendered":"Hard Against Drugs"},"content":{"rendered":"<p>LUEGO DE CUARENTA A\u00d1OS DE LUcha infructuosa contra las drogas il\u00edcitas \u2014todo empez\u00f3 cuando Richard Nixon la emprendi\u00f3 contra los hippies y los j\u00f3venes libertarios de los sesentas\u2014, hoy las opiniones de los partidarios de la legalizaci\u00f3n empiezan a ser tomadas en serio.<\/p>\n<p>\u00bfQu\u00e9 ha pasado para que esto finalmente suceda? \u00bfFueron acaso los argumentos de los acad\u00e9micos y cient\u00edficos sociales que durante a\u00f1os pusieron en evidencia la estupidez de esa guerra? \u00bfO tal vez fue el dolor de las innumerables v\u00edctimas que ha dejado esa cruzada puritana? \u00bfO fue quiz\u00e1s el efecto devastador de las mafias en pa\u00edses como Colombia, Afganist\u00e1n, Rusia o M\u00e9xico?<\/p>\n<p>Pues no, nada de eso. La convicci\u00f3n de los prohibicionistas no tambalea hoy por esas evidencias en su contra, sino por otra cosa: por el dinero que cuesta mantener a los prisioneros de esa guerra.<\/p>\n<p>El caso m\u00e1s dram\u00e1tico se vive en California, un Estado que tiene un d\u00e9ficit de 24 mil millones de d\u00f3lares, ocasionado por la desastrosa combinaci\u00f3n de dos pol\u00edticas conservadoras: la reducci\u00f3n de los impuestos, por un lado, y la decisi\u00f3n de actuar con dureza frente al consumo de drogas (Get tough on drugs), por el otro. Resultado: mientras hace treinta a\u00f1os el presupuesto destinado a las prisiones era la quinta parte del presupuesto destinado a la educaci\u00f3n, hoy ambos presupuestos son iguales y eso debido a que la poblaci\u00f3n carcelaria pas\u00f3 de 30 mil, a m\u00e1s de 150 mil. Algo parecido sucede en estados como Michigan, Vermont, Oregon, Delaware y Connecticut, entre otros.<\/p>\n<p>Ante semejante descalabro, muchos altos funcionarios est\u00e1n hoy dispuestos a discutir pol\u00edticas de legalizaci\u00f3n. Se estima que si los actuales consumidores de marihuana pagaran un peque\u00f1o impuesto al consumo, el Estado recolectar\u00eda mil trescientos millones de d\u00f3lares anuales. Eso no acabar\u00eda con el d\u00e9ficit actual, pero si a eso se le suma la liberaci\u00f3n de todos los que est\u00e1n en la c\u00e1rcel por fumarse un varillo, la soluci\u00f3n estar\u00eda muy cerca. Por eso, el gobernador Arnold Schwarzenegger \u2014republicano\u2014 ha dicho que el Estado de California est\u00e1 dispuesto a estudiar los m\u00e9ritos de las propuestas de legalizaci\u00f3n de la marihuana.<\/p>\n<p>Las razones que tiene Schwarzenegger para decir eso son, desde luego, muy distintas a las esgrimidas por los promotores de la legalizaci\u00f3n: no est\u00e1n fundadas en la defensa de la libertad, no tienen nada que ver con las razones humanitarias que han llevado a los jueces a exigir una mejor\u00eda en las condiciones de vida de los presos y tampoco tienen nada que ver con la lucha contra la discriminaci\u00f3n de los negros (mientras los consumidores blancos son cinco veces m\u00e1s numerosos que los negros, \u00e9stos \u00faltimos representan el 62% de los presos por drogas). Son razones simplemente econ\u00f3micas, las mismas que se esgrimen hoy en muchos estados para eliminar la pena de muerte, la cual, aunque no parezca, es mucho m\u00e1s costosa que la cadena perpetua.<\/p>\n<p>Pero a los defensores de la legalizaci\u00f3n les tiene sin cuidado que los prohibicionistas no crean en principios humanitarios o de libertad. Les basta con que, finalmente, los prohibicionistas sean consecuentes con lo que piensan, es decir, que reconozcan que la mejor manera de ser duros contra las drogas, es legaliz\u00e1ndolas.<\/p>\n<p>P.D. Mientras tanto, en Colombia avanza el proyecto de reforma constitucional para penalizar la dosis personal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>After forty years of a fruitless drug war that started out with Richard Nixon&#8217;s declaration against hippies and young libertarians of the 1960&#8217;s, today, legalizing supporters are being taken into account. <\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1022],"tags":[],"class_list":["post-26373","post","type-post","status-publish","format-standard","hentry","category-uncategorized","subcategory-drug-policy","medium-el-espectador-en","post-scope-aaa-not-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hard Against Drugs - Dejusticia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hard Against Drugs\" \/>\n<meta property=\"og:description\" content=\"After forty years of a fruitless drug war that started out with Richard Nixon&#039;s declaration against hippies and young libertarians of the 1960&#039;s, today, legalizing supporters are being taken into account.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dejusticia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dejusticia\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-11T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T12:31:31+00:00\" \/>\n<meta name=\"author\" content=\"Mauricio Garc\u00eda Villegas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:site\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauricio Garc\u00eda Villegas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\"},\"author\":{\"name\":\"Mauricio Garc\u00eda Villegas\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d5933ad4c269c4b6c2acbf717ceeb0d6\"},\"headline\":\"Hard Against Drugs\",\"datePublished\":\"2009-07-11T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:31:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"inLanguage\":\"en-US\",\"copyrightYear\":\"2009\",\"copyrightHolder\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\",\"url\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\",\"name\":\"Hard Against Drugs - Dejusticia\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#website\"},\"datePublished\":\"2009-07-11T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/develop.dejusticia.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hard Against Drugs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/develop.dejusticia.org\/#website\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"name\":\"Dejusticia\",\"description\":\"Centro de Estudios de Derecho, Justicia y Sociedad\",\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/develop.dejusticia.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\",\"name\":\"Dejusticia\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"contentUrl\":\"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"width\":1,\"height\":1,\"caption\":\"Dejusticia\"},\"image\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Dejusticia\/\",\"https:\/\/x.com\/dejusticia\",\"https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d5933ad4c269c4b6c2acbf717ceeb0d6\",\"name\":\"Mauricio Garc\u00eda Villegas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6789652e6645cb6eabc2b7e10095952474013398635e5aade12b153e3571a300?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6789652e6645cb6eabc2b7e10095952474013398635e5aade12b153e3571a300?s=96&d=mm&r=g\",\"caption\":\"Mauricio Garc\u00eda Villegas\"},\"url\":\"https:\/\/develop.dejusticia.org\/en\/responsible\/mauricio-garcia-villegas\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hard Against Drugs - Dejusticia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/","og_locale":"en_US","og_type":"article","og_title":"Hard Against Drugs","og_description":"After forty years of a fruitless drug war that started out with Richard Nixon's declaration against hippies and young libertarians of the 1960's, today, legalizing supporters are being taken into account.","og_url":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/","og_site_name":"Dejusticia","article_publisher":"https:\/\/www.facebook.com\/Dejusticia\/","article_published_time":"2009-07-11T05:00:00+00:00","article_modified_time":"2017-04-11T12:31:31+00:00","author":"Mauricio Garc\u00eda Villegas","twitter_card":"summary_large_image","twitter_creator":"@dejusticia","twitter_site":"@dejusticia","twitter_misc":{"Written by":"Mauricio Garc\u00eda Villegas","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","NewsArticle"],"@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#article","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/"},"author":{"name":"Mauricio Garc\u00eda Villegas","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d5933ad4c269c4b6c2acbf717ceeb0d6"},"headline":"Hard Against Drugs","datePublished":"2009-07-11T05:00:00+00:00","dateModified":"2017-04-11T12:31:31+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/"},"wordCount":595,"publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"inLanguage":"en-US","copyrightYear":"2009","copyrightHolder":{"@id":"https:\/\/develop.dejusticia.org\/#organization"}},{"@type":"WebPage","@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/","url":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/","name":"Hard Against Drugs - Dejusticia","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/#website"},"datePublished":"2009-07-11T05:00:00+00:00","dateModified":"2017-04-11T12:31:31+00:00","breadcrumb":{"@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/develop.dejusticia.org\/duro-contra-las-drogas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/develop.dejusticia.org\/en\/"},{"@type":"ListItem","position":2,"name":"Hard Against Drugs"}]},{"@type":"WebSite","@id":"https:\/\/develop.dejusticia.org\/#website","url":"https:\/\/develop.dejusticia.org\/","name":"Dejusticia","description":"Centro de Estudios de Derecho, Justicia y Sociedad","publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.dejusticia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/develop.dejusticia.org\/#organization","name":"Dejusticia","url":"https:\/\/develop.dejusticia.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/","url":"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","contentUrl":"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","width":1,"height":1,"caption":"Dejusticia"},"image":{"@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dejusticia\/","https:\/\/x.com\/dejusticia","https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed"]},{"@type":"Person","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/d5933ad4c269c4b6c2acbf717ceeb0d6","name":"Mauricio Garc\u00eda Villegas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6789652e6645cb6eabc2b7e10095952474013398635e5aade12b153e3571a300?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6789652e6645cb6eabc2b7e10095952474013398635e5aade12b153e3571a300?s=96&d=mm&r=g","caption":"Mauricio Garc\u00eda Villegas"},"url":"https:\/\/develop.dejusticia.org\/en\/responsible\/mauricio-garcia-villegas\/"}]}},"views":138,"translations":[{"en":{"translation_id":"9941","language_code":"en","element_id":"26373","source_language_code":"es","element_type":"post_post","original":"0","post_title":"Hard Against Drugs","post_status":"publish"},"es":{"translation_id":"9940","language_code":"es","element_id":"26372","source_language_code":null,"element_type":"post_post","original":"1","post_title":"Duro contra las drogas","post_status":"publish"}}],"_links":{"self":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/26373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/comments?post=26373"}],"version-history":[{"count":0,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/26373\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/media?parent=26373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/categories?post=26373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/tags?post=26373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}