{"id":26377,"date":"2009-07-11T00:00:00","date_gmt":"2009-07-11T05:00:00","guid":{"rendered":"https:\/\/www.dejusticia.org\/dejusticias-director-was-interviewed-by-the-magazine-poder-360-about-re-election-and-checks-and-balances\/"},"modified":"2017-04-11T07:31:35","modified_gmt":"2017-04-11T12:31:35","slug":"dejusticias-director-was-interviewed-by-the-magazine-poder-360-about-re-election-and-checks-and-balances","status":"publish","type":"post","link":"https:\/\/develop.dejusticia.org\/en\/dejusticias-director-was-interviewed-by-the-magazine-poder-360-about-re-election-and-checks-and-balances\/","title":{"rendered":"Dejusticia&#8217;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances"},"content":{"rendered":"<p>Pesos y m\u00e1s pesos<\/p>\n<p>Quienes se oponen a la segunda reelecci\u00f3n del presidente \u00c1lvaro Uribe sostienen que un tercer periodo afectar\u00eda profundamente el equilibrio de poderes. Pero hay expertos que aseguran que el da\u00f1o ya est\u00e1 hecho y que se producir\u00edan otros da\u00f1os, m\u00e1s sutiles, pero m\u00e1s profundos. Argumentos.<\/p>\n<p>Por Clara Elvira Ospina <\/p>\n<p>No est\u00e1 claro si la reelecci\u00f3n tenga futuro. La investigaci\u00f3n de la Corte Suprema contra los 86 representantes que votaron el proyecto de referendo en la madrugada del 17 de diciembre del a\u00f1o pasado en una jornada extrarr\u00e1pida de sesiones extras, y el creciente n\u00famero de ciudadanos habilitados para votar -lo que hace crecer el censo electoral y aumenta el umbral para que pase la reelecci\u00f3n- penden como espadas contra los planes reeleccionistas. Pero tampoco est\u00e1 claro que no haya reelecci\u00f3n. Los opositores tienen como argumento central en contra de la iniciativa el desequilibrio de poderes que se generar\u00eda con un tercer periodo.<\/p>\n<p>El centro de estudios Dejusticia, tal vez el que ha presentando m\u00e1s an\u00e1lisis acerca de este tema, sostiene que el da\u00f1o del desequilibrio ya est\u00e1 hecho y que una segunda reelecci\u00f3n simplemente ratificar\u00eda lo que ya ocurri\u00f3. \u201cEl Presidente, manifiesta el director de Dejusticia, Rodrigo Uprimny, ya tiene una influencia decisiva en la definici\u00f3n de quienes est\u00e1n en cabeza de los organismos de control o de las juntas del Banco de la Rep\u00fablica y la Comisi\u00f3n de Televisi\u00f3n. Lo que pasar\u00eda ser\u00eda que se perpetuar\u00eda ese control. La primera reelecci\u00f3n ya golpe\u00f3 seriamente la pol\u00edtica jur\u00eddica de contrapesos\u201d.<\/p>\n<p>En el fallo mediante el cual aprob\u00f3 el Acto Legislativo que le permiti\u00f3 a Uribe presentarse como candidato para un segundo periodo, la Corte Constitucional plante\u00f3 que era necesario que el Congreso legislara para reorganizar los equilibrios que se alteraban con la reelecci\u00f3n. En ese momento, la Corte dijo que \u201cse afectan ciertos elementos puntuales de la arquitectura constitucional, cuyo sentido podr\u00eda estar en cierta medida vinculado a la duraci\u00f3n del mandato presidencial, como podr\u00eda ser la participaci\u00f3n del Presidente en la integraci\u00f3n de otros \u00f3rganos del Estado, como la junta directiva del Banco de la Rep\u00fablica, la Sala Jurisdiccional del Consejo Superior de la Judicatura, la Fiscal\u00eda General de la Naci\u00f3n o la propia Corte Constitucional.<\/p>\n<p>La reelecci\u00f3n del Presidente proyectar\u00e1 por un periodo m\u00e1s su influencia en la conformaci\u00f3n de esos \u00f3rganos\u201d. Y as\u00ed fue. El estudio de Dejusticia (ver tabla) muestra claramente c\u00f3mo el Presidente asumi\u00f3 el control, por nominaci\u00f3n, de la Sala Disciplinaria del Consejo Superior de la Judicatura, la Junta del Banco de la Rep\u00fablica, la Fiscal\u00eda y la Defensor\u00eda del Pueblo y por influencia de su bancada, en la Corte Constitucional, la Procuradur\u00eda, la Contralor\u00eda y la Comisi\u00f3n Nacional de Televisi\u00f3n.<\/p>\n<p>Organismos de control<\/p>\n<p>Una vez aprobada la reelecci\u00f3n, el senador liberal Juan Fernando Cristo present\u00f3 un proyecto de acto legislativo que modificaba todos los sistemas de elecci\u00f3n y nominaci\u00f3n de estos funcionarios para equilibrar los poderes. El proyecto se hundi\u00f3 sin pena ni gloria, pero los argumentos siguen vigentes. Dice la exposici\u00f3n de motivos que \u201cuno de los objetivos de la Constituci\u00f3n de 1991 fue restar la preponderancia del Ejecutivo sobre el resto de las ramas del poder p\u00fablico, preponderancia que hab\u00eda adquirido a trav\u00e9s de las distintas reformas que se introdujeron a la Constituci\u00f3n de 1886\u201d. En esa misma l\u00ednea habla el abogado constitucionalista Juan Manuel Charry, quien afirma que \u201cla Constituci\u00f3n del 91 fue dise\u00f1ada para periodos presidenciales de cuatro a\u00f1os. Los constituyentes gastaron tiempo en sincronizar los periodos de funcionarios para que fueran intercalados, pero la primera reelecci\u00f3n ya alter\u00f3 ese dise\u00f1o\u201d.<\/p>\n<p>En el caso de los \u00f3rganos de control, la influencia presidencial es inmensa. El Presidente logr\u00f3 tener un fiscal que hizo parte de su gobierno, Mario Iguar\u00e1n, y ahora tendr\u00e1 otro de sus afectos. Hace dos semanas present\u00f3 la terna, de la que forman parte una abogada amiga suya, un ex consejero muy cercano a su gesti\u00f3n en la Gobernaci\u00f3n de Antioquia y un ex asesor, ex ministro y ex embajador de este gobierno. En la Procuradur\u00eda, Uribe logr\u00f3 que el Congreso eligiera al candidato del Consejo de Estado, que era el que le gustaba al Gobierno. Igual ocurri\u00f3 en la Contralor\u00eda General.<\/p>\n<p>El otro caso, sin duda, relevante es el de la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura. El Presidente nomina a todos sus integrantes. El abogado Charry resalta que es por ah\u00ed por donde han entrado varias tutelas de la parapol\u00edtica y la del ministro Palacio contra la Corte Constitucional. Para Uprimny, el poder sobre la sala disciplinaria va m\u00e1s all\u00e1, pues esa sala investiga y sanciona a jueces y abogados de todo el pa\u00eds, salvo a los magistrados con fuero: \u201cEl riesgo es que por compromisos pol\u00edticos no investigue arbitrariedades de jueces o que persiga a jueces y abogados independientes. As\u00ed que por la v\u00eda de la Sala Disciplinaria, el presidente s\u00ed adquiere un poder indirecto inmenso sobre la rama judicial\u201d.<br \/>\nEl caso de la Corte Constitucional genera m\u00e1s controversia. Hay quienes opinan que en esa corporaci\u00f3n hay m\u00e1s tradici\u00f3n de independencia. Sin embargo, las cuentas son reveladoras: el presidente nomina a tres de los siete magistrados (Mar\u00eda Victoria Calle, Jorge Pretelt y Mauricio Gonz\u00e1lez), pero incidi\u00f3 claramente con su bancada para la elecci\u00f3n de otros tres: Nilson Pinilla y Jorge Iv\u00e1n Palacio, nominados por la Corte Suprema, y Gabriel Mendoza, nominado por el Consejo de Estado. As\u00ed, ya tendr\u00eda seis de los nueve votos posibles en las decisiones. Pero es conocido que al menos la magistrada Calle ha mantenido una clara independencia del Gobierno, en virtud de lo que se ha llamado en historia de las ideas pol\u00edticas \u201cel deber de la ingratitud\u201dcon el nominador.<br \/>\nEl ejemplo de la junta del Banco de la Rep\u00fablica es usado con frecuencia para se\u00f1alar que no necesariamente la nominaci\u00f3n garantiza complicidad o solidaridad con el nominador. La junta, que ya toda fue nombrada por el Presidente, ha mantenido su independencia. Uprimny y Charry coinciden en que ah\u00ed est\u00e1 la excepci\u00f3n que confirma la regla: los escogidos son de alt\u00edsimas calidades t\u00e9cnicas y han tenido una tradici\u00f3n de independencia.<\/p>\n<p>Inestabilidad en las reglas<\/p>\n<p>Para el director de Dejusticia, la segunda reelecci\u00f3n tendr\u00eda efectos m\u00e1s contundentes en otros dos pilares de los principios democr\u00e1ticos: la alternancia y el no caudillismo. En el primer punto, Uprimny aseguras que \u201clos gobiernos y los partidos necesitan la alternancia para garantizar sustentos de la democracia como que quienes son minor\u00eda tengan la garant\u00eda de que sus derechos ser\u00e1n respetados y que esas minor\u00edas tengan al menos la expectativa de que alg\u00fan d\u00eda pueden llegar a ser mayor\u00eda y a estar en el poder\u201d.<\/p>\n<p>En el otro principio, el del no caudillismo, Uprimny cita a Barber, un polit\u00f3logo que asevera que \u201clo que distingue a las buenas de las malas democracias no es que tengan buenos l\u00edderes, sino que tengan buenos ciudadanos\u201d. Y asegura que una democracia se altera profundamente cuando se modifican las reglas de juego a favor de alguien, porque el Estado de Derecho es de leyes y no de personas: \u201cEn virtud del Estado de Derecho, debe haber estabilidad en las reglas e incertidumbre en los procesos pol\u00edticos, pero aqu\u00ed quieren que haya inestabilidad en las reglas y certidumbre en los procesos. Eso es contrario a los valores democr\u00e1ticos\u201d.<br \/>\nAh\u00ed quedan m\u00e1s elementos para el an\u00e1lisis.<\/p>\n<p>Disponible en: http:\/\/www.poder360.com\/article_detail.php?id_article=2167<\/p>\n","protected":false},"excerpt":{"rendered":"<p>More checks and balances.<\/p>\n<p>One of the principal arguments exposed by those who oppose Uribe&#8217;s second re-election is the disturbance of the balance of power. Notwithstanding, some experts say damage has already been done and will continue being done. <\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1022],"tags":[],"class_list":["post-26377","post","type-post","status-publish","format-standard","hentry","category-uncategorized","medium-poder-360-en","post-scope-aaa-not-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dejusticia&#039;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances - Dejusticia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dejusticia&#039;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances\" \/>\n<meta property=\"og:description\" content=\"More checks and balances.  One of the principal arguments exposed by those who oppose Uribe&#039;s second re-election is the disturbance of the balance of power. Notwithstanding, some experts say damage has already been done and will continue being done.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\" \/>\n<meta property=\"og:site_name\" content=\"Dejusticia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dejusticia\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-11T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T12:31:35+00:00\" \/>\n<meta name=\"author\" content=\"Dejusticia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:site\" content=\"@dejusticia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dejusticia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\"},\"author\":{\"name\":\"Dejusticia\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/76344004e81d3b86a24b524c67cd939d\"},\"headline\":\"Dejusticia&#8217;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances\",\"datePublished\":\"2009-07-11T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:31:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\"},\"wordCount\":1356,\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"inLanguage\":\"en-US\",\"copyrightYear\":\"2009\",\"copyrightHolder\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\",\"url\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\",\"name\":\"Dejusticia's Director was interviewed by the magazine Poder 360 about re-election and checks and balances - Dejusticia\",\"isPartOf\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#website\"},\"datePublished\":\"2009-07-11T05:00:00+00:00\",\"dateModified\":\"2017-04-11T12:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/develop.dejusticia.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dejusticia&#8217;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/develop.dejusticia.org\/#website\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"name\":\"Dejusticia\",\"description\":\"Centro de Estudios de Derecho, Justicia y Sociedad\",\"publisher\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/develop.dejusticia.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/develop.dejusticia.org\/#organization\",\"name\":\"Dejusticia\",\"url\":\"https:\/\/develop.dejusticia.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"contentUrl\":\"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg\",\"width\":1,\"height\":1,\"caption\":\"Dejusticia\"},\"image\":{\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Dejusticia\/\",\"https:\/\/x.com\/dejusticia\",\"https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/76344004e81d3b86a24b524c67cd939d\",\"name\":\"Dejusticia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5ad1255f2294011be0bbf83455e00549e04bd4ae56d6213a5e335c9828621990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5ad1255f2294011be0bbf83455e00549e04bd4ae56d6213a5e335c9828621990?s=96&d=mm&r=g\",\"caption\":\"Dejusticia\"},\"url\":\"https:\/\/develop.dejusticia.org\/en\/responsible\/dejusticia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dejusticia's Director was interviewed by the magazine Poder 360 about re-election and checks and balances - Dejusticia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/","og_locale":"en_US","og_type":"article","og_title":"Dejusticia's Director was interviewed by the magazine Poder 360 about re-election and checks and balances","og_description":"More checks and balances.  One of the principal arguments exposed by those who oppose Uribe's second re-election is the disturbance of the balance of power. Notwithstanding, some experts say damage has already been done and will continue being done.","og_url":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/","og_site_name":"Dejusticia","article_publisher":"https:\/\/www.facebook.com\/Dejusticia\/","article_published_time":"2009-07-11T05:00:00+00:00","article_modified_time":"2017-04-11T12:31:35+00:00","author":"Dejusticia","twitter_card":"summary_large_image","twitter_creator":"@dejusticia","twitter_site":"@dejusticia","twitter_misc":{"Written by":"Dejusticia","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","NewsArticle"],"@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#article","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/"},"author":{"name":"Dejusticia","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/76344004e81d3b86a24b524c67cd939d"},"headline":"Dejusticia&#8217;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances","datePublished":"2009-07-11T05:00:00+00:00","dateModified":"2017-04-11T12:31:35+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/"},"wordCount":1356,"publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"inLanguage":"en-US","copyrightYear":"2009","copyrightHolder":{"@id":"https:\/\/develop.dejusticia.org\/#organization"}},{"@type":"WebPage","@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/","url":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/","name":"Dejusticia's Director was interviewed by the magazine Poder 360 about re-election and checks and balances - Dejusticia","isPartOf":{"@id":"https:\/\/develop.dejusticia.org\/#website"},"datePublished":"2009-07-11T05:00:00+00:00","dateModified":"2017-04-11T12:31:35+00:00","breadcrumb":{"@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/develop.dejusticia.org\/revista-poder-360-entrevista-a-director-de-dejusticia-sobre-reeleccion-y-frenos-y-contrapesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/develop.dejusticia.org\/en\/"},{"@type":"ListItem","position":2,"name":"Dejusticia&#8217;s Director was interviewed by the magazine Poder 360 about re-election and checks and balances"}]},{"@type":"WebSite","@id":"https:\/\/develop.dejusticia.org\/#website","url":"https:\/\/develop.dejusticia.org\/","name":"Dejusticia","description":"Centro de Estudios de Derecho, Justicia y Sociedad","publisher":{"@id":"https:\/\/develop.dejusticia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.dejusticia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/develop.dejusticia.org\/#organization","name":"Dejusticia","url":"https:\/\/develop.dejusticia.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/","url":"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","contentUrl":"https:\/\/develop.dejusticia.org\/wp-content\/uploads\/2020\/09\/logo-v1-dejusticia-MC.svg","width":1,"height":1,"caption":"Dejusticia"},"image":{"@id":"https:\/\/develop.dejusticia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dejusticia\/","https:\/\/x.com\/dejusticia","https:\/\/www.youtube.com\/channel\/UCbwnwY8oIpHCug4R3KhjewQ\/feed"]},{"@type":"Person","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/76344004e81d3b86a24b524c67cd939d","name":"Dejusticia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/develop.dejusticia.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5ad1255f2294011be0bbf83455e00549e04bd4ae56d6213a5e335c9828621990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ad1255f2294011be0bbf83455e00549e04bd4ae56d6213a5e335c9828621990?s=96&d=mm&r=g","caption":"Dejusticia"},"url":"https:\/\/develop.dejusticia.org\/en\/responsible\/dejusticia\/"}]}},"views":197,"translations":[{"en":{"translation_id":"9945","language_code":"en","element_id":"26377","source_language_code":"es","element_type":"post_post","original":"0","post_title":"Dejusticia's Director was interviewed by the magazine Poder 360 about re-election and checks and balances","post_status":"publish"},"es":{"translation_id":"9944","language_code":"es","element_id":"26376","source_language_code":null,"element_type":"post_post","original":"1","post_title":"Revista Poder 360 entrevista a Director de Dejusticia sobre  reelecci\u00f3n y  frenos y contrapesos","post_status":"publish"}}],"_links":{"self":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/26377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/comments?post=26377"}],"version-history":[{"count":0,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/posts\/26377\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/media?parent=26377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/categories?post=26377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.dejusticia.org\/en\/wp-json\/wp\/v2\/tags?post=26377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}